{"id":974,"date":"2023-11-02T07:29:58","date_gmt":"2023-11-02T07:29:58","guid":{"rendered":"https:\/\/www.gaialeadership.com\/?p=974"},"modified":"2024-04-19T08:02:00","modified_gmt":"2024-04-19T06:02:00","slug":"interaction","status":"publish","type":"post","link":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/","title":{"rendered":"Interaction"},"content":{"rendered":"<p style=\"font-weight: 400;\">What is interaction? Inter &#8211; between. Action &#8211; doing, acting. The middle ground.<\/p>\n<p style=\"font-weight: 400;\">We often long for interaction. A real meeting where we focus on something we have between us.<\/p>\n<p style=\"font-weight: 400;\">And at the same time, we talk a lot about the need for collaboration. Many organizations are struggling to increase collaboration, build collaborative cultures.<\/p>\n<p style=\"font-weight: 400;\">Several buzzwords here: collaboration, co-creation, cooperation.<\/p>\n<p>Sometimes it is interesting and clarifying to look in to the actual meaning of a word. Especially to look at what sets it apart from other words that we might use as synonyms.<\/p>\n<p style=\"font-weight: 400;\">Co- as a prefix means something that is common, shared.<\/p>\n<p style=\"font-weight: 400;\">An interesting difference compared to the prefix inter-. Inter as a prefix points to something that is between us.<\/p>\n<p style=\"font-weight: 400;\">When the meeting and what we are going to do together are placed between us, instead of it being immediately shared, it might create more space for action. And perhaps even more important: a space for seeing more clearly, seeing the different perspectives and degrees of complexity.<\/p>\n<p style=\"font-weight: 400;\">And that space can also allow for a meeting between independent parties, where different perspectives can create movement and new insight.<\/p>\n<p style=\"font-weight: 400;\">Sometimes we might be helped by choosing interaction rather than collaboration. That we choose, as a mindset, to <strong>not<\/strong> make the task at hand shared. Instead we can choose to place it between us and work in that space, in the meeting between our perspectives. \u00a0Then it creates a better arena for the collaboration, co-creation, and cooperation that we always need to engage in, sooner or later, to create results and value.<\/p>\n<p>To read more about our thoughts in the need for co-creation and collaboration, read about <a href=\"https:\/\/www.gaialeadership.com\/en\/gaia-mindset-2\/\">Gaia Mindset<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>What is interaction? Inter &#8211; between. Action &#8211; doing, acting. The middle ground. We often long for interaction&#8230;.<\/p>\n","protected":false},"author":5,"featured_media":844,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-974","post","type-post","status-publish","format-standard","has-post-thumbnail","category-okategoriserad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interaction - Gaia Leadership<\/title>\n<meta name=\"description\" content=\"We often long for interaction. But we talk more about collaboration. Is there a difference between the two?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interaction - Gaia Leadership\" \/>\n<meta property=\"og:description\" content=\"We often long for interaction. But we talk more about collaboration. Is there a difference between the two?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaia Leadership\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-02T07:29:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T06:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/08\/IMG_8056-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Wilhelmsson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Wilhelmsson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/\"},\"author\":{\"name\":\"Anna Wilhelmsson\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#\\\/schema\\\/person\\\/d0f3c98f79072656b635fff822698f70\"},\"headline\":\"Interaction\",\"datePublished\":\"2023-11-02T07:29:58+00:00\",\"dateModified\":\"2024-04-19T06:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/\"},\"wordCount\":280,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gaialeadership.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG_8056-scaled.jpg\",\"articleSection\":[\"Okategoriserad\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/\",\"url\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/\",\"name\":\"Interaction - Gaia Leadership\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gaialeadership.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG_8056-scaled.jpg\",\"datePublished\":\"2023-11-02T07:29:58+00:00\",\"dateModified\":\"2024-04-19T06:02:00+00:00\",\"description\":\"We often long for interaction. But we talk more about collaboration. Is there a difference between the two?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gaialeadership.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG_8056-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gaialeadership.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/IMG_8056-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Gaia interaction\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/reflections\\\/interaction\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interaction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/\",\"name\":\"Gaia Leadership\",\"description\":\"Gaia Leadership\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#organization\",\"name\":\"Gaia Leadership\",\"url\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gaialeadership.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/gaila-logo-dark.svg\",\"contentUrl\":\"https:\\\/\\\/www.gaialeadership.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/gaila-logo-dark.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Gaia Leadership\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gaia-leadership\\\/\",\"https:\\\/\\\/www.instagram.com\\\/gaialeadership\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/#\\\/schema\\\/person\\\/d0f3c98f79072656b635fff822698f70\",\"name\":\"Anna Wilhelmsson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/295de1f63c90954b6f72f78cfbb630d54d48a5be58d9ef2b30735e7e95fb7261?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/295de1f63c90954b6f72f78cfbb630d54d48a5be58d9ef2b30735e7e95fb7261?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/295de1f63c90954b6f72f78cfbb630d54d48a5be58d9ef2b30735e7e95fb7261?s=96&d=mm&r=g\",\"caption\":\"Anna Wilhelmsson\"},\"url\":\"https:\\\/\\\/www.gaialeadership.com\\\/en\\\/author\\\/annawilhelmssonprod\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interaction - Gaia Leadership","description":"We often long for interaction. But we talk more about collaboration. Is there a difference between the two?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/","og_locale":"en_US","og_type":"article","og_title":"Interaction - Gaia Leadership","og_description":"We often long for interaction. But we talk more about collaboration. Is there a difference between the two?","og_url":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/","og_site_name":"Gaia Leadership","article_published_time":"2023-11-02T07:29:58+00:00","article_modified_time":"2024-04-19T06:02:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/08\/IMG_8056-scaled.jpg","type":"image\/jpeg"}],"author":"Anna Wilhelmsson","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Anna Wilhelmsson","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#article","isPartOf":{"@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/"},"author":{"name":"Anna Wilhelmsson","@id":"https:\/\/www.gaialeadership.com\/en\/#\/schema\/person\/d0f3c98f79072656b635fff822698f70"},"headline":"Interaction","datePublished":"2023-11-02T07:29:58+00:00","dateModified":"2024-04-19T06:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/"},"wordCount":280,"publisher":{"@id":"https:\/\/www.gaialeadership.com\/en\/#organization"},"image":{"@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/08\/IMG_8056-scaled.jpg","articleSection":["Okategoriserad"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/","url":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/","name":"Interaction - Gaia Leadership","isPartOf":{"@id":"https:\/\/www.gaialeadership.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#primaryimage"},"image":{"@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/08\/IMG_8056-scaled.jpg","datePublished":"2023-11-02T07:29:58+00:00","dateModified":"2024-04-19T06:02:00+00:00","description":"We often long for interaction. But we talk more about collaboration. Is there a difference between the two?","breadcrumb":{"@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#primaryimage","url":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/08\/IMG_8056-scaled.jpg","contentUrl":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/08\/IMG_8056-scaled.jpg","width":2560,"height":1920,"caption":"Gaia interaction"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gaialeadership.com\/en\/reflections\/interaction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/www.gaialeadership.com\/en\/"},{"@type":"ListItem","position":2,"name":"Interaction"}]},{"@type":"WebSite","@id":"https:\/\/www.gaialeadership.com\/en\/#website","url":"https:\/\/www.gaialeadership.com\/en\/","name":"Gaia Leadership","description":"Gaia Leadership","publisher":{"@id":"https:\/\/www.gaialeadership.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gaialeadership.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.gaialeadership.com\/en\/#organization","name":"Gaia Leadership","url":"https:\/\/www.gaialeadership.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.gaialeadership.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/07\/gaila-logo-dark.svg","contentUrl":"https:\/\/www.gaialeadership.com\/wp-content\/uploads\/2023\/07\/gaila-logo-dark.svg","width":"1024","height":"1024","caption":"Gaia Leadership"},"image":{"@id":"https:\/\/www.gaialeadership.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/gaia-leadership\/","https:\/\/www.instagram.com\/gaialeadership\/"]},{"@type":"Person","@id":"https:\/\/www.gaialeadership.com\/en\/#\/schema\/person\/d0f3c98f79072656b635fff822698f70","name":"Anna Wilhelmsson","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/295de1f63c90954b6f72f78cfbb630d54d48a5be58d9ef2b30735e7e95fb7261?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/295de1f63c90954b6f72f78cfbb630d54d48a5be58d9ef2b30735e7e95fb7261?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/295de1f63c90954b6f72f78cfbb630d54d48a5be58d9ef2b30735e7e95fb7261?s=96&d=mm&r=g","caption":"Anna Wilhelmsson"},"url":"https:\/\/www.gaialeadership.com\/en\/author\/annawilhelmssonprod\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/posts\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/comments?post=974"}],"version-history":[{"count":0,"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/posts\/974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/media\/844"}],"wp:attachment":[{"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/categories?post=974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaialeadership.com\/en\/wp-json\/wp\/v2\/tags?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}